{"id":77059,"date":"2026-03-26T12:15:02","date_gmt":"2026-03-26T16:15:02","guid":{"rendered":"https:\/\/cyclingcanada.ca\/?post_type=news&#038;p=77059"},"modified":"2026-03-26T12:15:04","modified_gmt":"2026-03-26T16:15:04","slug":"les-championnats-canadiens-sur-piste-2026-u17-jr-se-deroulent-a-edmonton-ce-week-end","status":"publish","type":"news","link":"https:\/\/cyclingcanada.ca\/fr\/news\/les-championnats-canadiens-sur-piste-2026-u17-jr-se-deroulent-a-edmonton-ce-week-end\/","title":{"rendered":"LES CHAMPIONNATS CANADIENS SUR PISTE 2026 (U17\/JR) SE D\u00c9ROULENT \u00c0 EDMONTON CE WEEK\u2011END\u00a0"},"content":{"rendered":"\n<p><strong>OTTAWA, ON (26 mars 2026) \u2013&nbsp;<\/strong>Les meilleurs cyclistes sur piste des cat\u00e9gories U17 et Junior du pays se r\u00e9uniront \u00e0 Edmonton, en Alberta, du 27 au 29 mars 2026 pour les Championnats canadiens sur piste 2026 (U17\/Jr), un moment fort du calendrier national de Cyclisme Canada et une \u00e9tape essentielle dans le parcours de haute performance des jeunes athl\u00e8tes.<\/p>\n\n\n\n<p>Jen Eaton, responsable des \u00e9v\u00e9nements et des officiels chez Cyclisme Canada, a soulign\u00e9 : \u00ab Nous sommes ravis d\u2019accueillir les meilleurs jeunes cyclistes du pays aux Championnats canadiens sur piste 2026 pour les moins de 17 ans et les juniors, qui se d\u00e9rouleront cette ann\u00e9e au Coronation Park Sport and Recreation Centre, r\u00e9cemment inaugur\u00e9 \u00e0 Edmonton. \u00bb Elle a ajout\u00e9 : \u00ab Cette installation ultramoderne offre aux jeunes athl\u00e8tes un cadre inspirant pour tester leurs capacit\u00e9s, repousser leurs limites et continuer \u00e0 fa\u00e7onner l\u2019avenir du cyclisme canadien. Nous sommes impatients d\u2019assister aux performances remarquables et de d\u00e9couvrir les talents \u00e9mergents qui se r\u00e9v\u00e9leront tout au long des championnats. \u00bb&nbsp;<\/p>\n\n\n\n<p>Organis\u00e9s en collaboration avec l\u2019Alberta Velodrome Association, les Championnats auront lieu au nouveau v\u00e9lodrome int\u00e9rieur d\u2019Edmonton, marquant une \u00e9tape importante pour le cyclisme sur piste dans l\u2019Ouest canadien puisqu\u2019il s\u2019agit des premiers championnats nationaux tenus dans cette installation. Les athl\u00e8tes des cat\u00e9gories U17 et Junior se disputeront le prestigieux maillot \u00e0 feuille d\u2019\u00e9rable dans un programme complet d\u2019\u00e9preuves nationales, avec trois jours de comp\u00e9titions couvrant les disciplines de sprint et d\u2019endurance.<\/p>\n\n\n\n<p>La liste des participants comprend plusieurs champions de 2025 de retour pour d\u00e9fendre leur titre, ainsi que de nouveaux talents pr\u00eats \u00e0 monter sur le podium. Parmi les athl\u00e8tes \u00e0 surveiller, on retrouve Alexandra Fangeat, qui avait marqu\u00e9 les derniers championnats en \u00e9tablissant un record du monde dans la poursuite individuelle Junior et en d\u00e9montrant sa capacit\u00e9 \u00e0 dominer m\u00eame apr\u00e8s \u00eatre pass\u00e9e de la cat\u00e9gorie U17 \u00e0 Junior. Fangeat sera entour\u00e9 d&#8217;une solide \u00e9quipe compos\u00e9e d&#8217;autres champions de 2025.<\/p>\n\n\n\n<p>Pour plus d\u2019information, incluant le Guide technique et les mises \u00e0 jour de l\u2019\u00e9v\u00e9nement, veuillez consulter&nbsp;<a href=\"https:\/\/cyclingcanada.ca\/fr\/event\/championnats-canadiens-piste-2026-u17-jr\/\" target=\"_blank\" rel=\"noreferrer noopener\">la page officielle de l\u2019\u00e9v\u00e9nement<\/a>&nbsp;sur le site de Cyclisme Canada.<\/p>\n","protected":false},"featured_media":77058,"template":"","meta":{"_acf_changed":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false},"sport":[69],"class_list":["post-77059","news","type-news","status-publish","has-post-thumbnail","hentry","sport-piste"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cyclingcanada.ca\/fr\/wp-json\/wp\/v2\/news\/77059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingcanada.ca\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/cyclingcanada.ca\/fr\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingcanada.ca\/fr\/wp-json\/wp\/v2\/media\/77058"}],"wp:attachment":[{"href":"https:\/\/cyclingcanada.ca\/fr\/wp-json\/wp\/v2\/media?parent=77059"}],"wp:term":[{"taxonomy":"sport","embeddable":true,"href":"https:\/\/cyclingcanada.ca\/fr\/wp-json\/wp\/v2\/sport?post=77059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}